{"id":1485,"date":"2022-10-31T17:49:00","date_gmt":"2022-10-31T23:49:00","guid":{"rendered":"http:\/\/ceesp.org.mx\/?p=1485"},"modified":"2022-11-07T17:50:59","modified_gmt":"2022-11-07T23:50:59","slug":"el-proyecto-de-enmiendas-constitucionales-sobre-el-sistema-electoral","status":"publish","type":"post","link":"https:\/\/ceesp.org.mx\/index.php\/2022\/10\/31\/el-proyecto-de-enmiendas-constitucionales-sobre-el-sistema-electoral\/","title":{"rendered":"EL PROYECTO DE ENMIENDAS CONSTITUCIONALES SOBRE EL SISTEMA ELECTORAL"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<p>Opini\u00f3n de la Comisi\u00f3n de Venecia<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/ceesp.org.mx\/wp-content\/uploads\/2022\/11\/Analisis-Politico-261022.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Incrustado de Analisis-Politico-261022..\"><\/object><a id=\"wp-block-file--media-54b09386-0383-43f4-b47e-4148de054e25\" href=\"http:\/\/ceesp.org.mx\/wp-content\/uploads\/2022\/11\/Analisis-Politico-261022.pdf\">Analisis-Politico-261022<\/a><a href=\"http:\/\/ceesp.org.mx\/wp-content\/uploads\/2022\/11\/Analisis-Politico-261022.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-54b09386-0383-43f4-b47e-4148de054e25\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Opini\u00f3n de la Comisi\u00f3n de Venecia<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1485","post","type-post","status-publish","format-standard","hentry","category-la-semana-en-politica"],"_links":{"self":[{"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1485"}],"version-history":[{"count":1,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1485\/revisions"}],"predecessor-version":[{"id":1487,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1485\/revisions\/1487"}],"wp:attachment":[{"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceesp.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}